{"id":184529,"date":"2025-07-06T01:49:18","date_gmt":"2025-07-05T23:49:18","guid":{"rendered":"https:\/\/www.unipi.it\/ateneo\/organizzazione\/persone\/caterina-cristallini-84905-en\/"},"modified":"2026-04-01T04:36:47","modified_gmt":"2026-04-01T02:36:47","slug":"caterina-cristallini-84905-en","status":"publish","type":"unipi_persone","link":"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/","title":{"rendered":"Caterina Cristallini"},"content":{"rendered":"<p>Docente Esterno | Email: C.CRISTALLINI@ING.UNIPI.IT<\/p>\n","protected":false},"template":"","meta":{"unipi-persone-chiave":"84905","unipi-persone-nome":"Caterina","unipi-persone-cognome":"Cristallini","unipi-persone-email":"C.CRISTALLINI@ING.UNIPI.IT","unipi-persone-cv":"Caterina Cristallini, PhD in Biomateriali, Primo Ricercatore CNR, Professore Modulo di Chimica per Ingegneria dell'Energia<br \/>\r\n <br \/>\r\nDal 1997 al 1998 le \u00e8 stato conferito un incarico di ricerca per la produzione e la caratterizzazione di membrane per la ricrescita guidata dei tessuti nell\u2019ambito di un contratto di ricerca dell\u2019Universit\u00e0 di Pisa. <br \/>\r\nDal 1998 al 1999 ha svolta attivit\u00e0 di ricerca nell\u2019ambito di una borsa di studio post-dottorato relativamente all\u2019area scientifico-disciplinare di Ingegneria Industriale.<br \/>\r\nNel 1999 le \u00e8 stato conferito dall\u2019Universit\u00e0 di Pisa un Assegno di Ricerca sul tema \u201cProduzione e caratterizzazione di nuovi materiali polimerici bioartificiali\u201d. <br \/>\r\nIn data 18 dicembre 2001 \u00e8 ricercatore del Consiglio Nazionale delle Ricerche, III livello \u2013 profilo Ricercatore.  Fino al 2014 ha svolto la sua attivit\u00e0 di ricerca nella sezione di Pisa dell\u2019Istituto per i Polimeri, Compositi e Biomateriali IPCB, ex Istituto per i Materiali Compositi e Biomedici di Napoli (IMCB). <br \/>\r\nAttualmente \u00e8 afferente alla sede di Pisa dell\u2019Istituto per i Processi Chimico-Fisici (IPCF), presso il Dipartimento di Ingegneria Civile e Industriale dell\u2019Universit\u00e0 di Pisa.<br \/>\r\nNel 2014 ha ricevuto l\u2019abilitazione come Professore Associato nel settore ING-IND 22<br \/>\r\nNel 2016 \u00e8 stata nominata, sulla base di una selezione per titoli, Primo Ricercatore CNR \u2013 II livello per la Macro Area Dipartimentale: Scienze Chimiche e Tecnologie dei Materiali <br \/>\r\n<br \/>\r\nNel corso degli anni ha applicato la sua esperienza nel campo dei biomateriali e principalmente nei settori della scienza dei materiali polimerici, dell'ingegneria tessutale, del rilascio controllato di farmaci e delle nanotecnologie. Le linee di ricerca pi\u00f9 recenti riguardano:<br \/>\r\n1. Produzione di  materiali polimerici micro-nano strutturati o iniettabili  per il settore cardiovascolare;<br \/>\r\n2. Preparazione di nano particelle intelligenti e nano capsule termoreversibili per il trattamento di processi tumorali; <br \/>\r\n3.  Micro-nanotecnologie e strategie di terapia genica per il trattamento delle malattie genetiche;<br \/>\r\n4. Produzione e caratterizzazione di materiali polimerici intelligenti per il trattamento di malattie neurodegenerative;<br \/>\r\n5.  Nuovi materiali per il rivestimento di dispositivi impiantabili a livello intraperitoneale;<br \/>\r\n6. Studio in vitro dell\u2019interazione cellula-nanomateriale per la valutazione dell\u2019impatto e della sicurezza dei nanomateriali sulla salute umana.<br \/>\r\n<br \/>\r\nLe attivit\u00e0 di ricerca sono state condotte nell'ambito di diversi progetti di ricerca sia europei sia ministeriali (MIUR, bandi regionali, progetti FP7), per alcuni di questi \u00e8 stata Responsabile Scientifico. <br \/>\r\nAttualmente \u00e8 Coordinatore scientifico di un progetto europeo transnazionale call M-Era.net 2016 (2018-2021). <br \/>\r\nE\u2019 stata relatore di numerose tesi di laurea e di dottorato (totale 86) in Ingegneria Biomedica, Ingegneria Chimica e Chimica Industriale e Chimica Farmaceutica. E\u2019 stata tutor per studenti nell\u2019ambito di Erasmus e scuola alternanza lavoro. <br \/>\r\n<br \/>\r\nDal 2002 al 2012 \u00e8 stata Professore per il corso di Ingegneria Biomolecolare e Cellulare per la laurea Magistrale in Ingegneria Biomedica dell\u2019Universit\u00e0 di Pisa.  <br \/>\r\nDal 2011 ad oggi \u00e8 Professore per l\u2019Insegnamento di Chimica del corso di Chimica e Principi Chimici per il corso di Laurea Triennale in Ingegneria dell\u2019Energia dell\u2019Universit\u00e0 di Pisa. <br \/>\r\n<br \/>\r\nNel 2008 \u00e8 stata Presidente del Congresso Nazionale di Biomateriali. E\u2019 stata relatore e moderatore in molti congressi nazionali e internazionali. Ha partecipato al Comitato Internazionale Advisory Board per la rivista Journal of Applied Biomaterials & Functional Materials Wichtig. Ha svolto e svolge attivit\u00e0 di referaggio per numerose riviste internazionali.<br \/>\r\nE\u2019 membro e segretario della Societ\u00e0 Italiana di Biomateriali. <br \/>\r\n <br \/>\r\nL\u2019attivit\u00e0 scientifica svolta fino ad oggi ha prodotto: 108 pubblicazioni su riviste nazionali ed internazionali, 121 comunicazioni a congressi nazionali ed internazionali e 3 brevetti.","unipi-persone-modalita-ricevimento":"l'orario pu\u00f2 essere concordato previa comunicazione email con il docente ","unipi-persone-luogo-ricevimento":"\r\nScuola Ingegneria, DICI Polo A sede Ingegneria Chimica","unipi-persone-ore-ricevimento":"\r\ngioved\u00ec pomeriggio ore 17-18","unipi-persone-link-orario-lezioni":"https:\/\/unipi.prod.up.cineca.it\/calendarioPubblico\/matricola=11904 ","unipi-persone-link-registro-lezioni":"https:\/\/unimap.unipi.it\/registri\/registri.php?ri=11904 &tmplt=principale.tpl","unipi-persone-ruolo":"Docente Esterno","unipi-persone-arpi":"https:\/\/arpi.unipi.it\/cris\/rp\/rp08432","unipi-persone-codocenze":"<h4 class=\"mt-2\">Incarichi di co-docenza in moduli\/insegnamenti<\/h4><ul><li>Chimica (Modulo dell&#039;insegnamento Chimica e Processi Chimici Cod. 004CI) per Laurea in Ingegneria dell&#039;energia<\/li><\/ul>","_wpml_word_count":"8","_last_translation_edit_mode":"translation-editor","unipi-persone-pubblicazioni":"<ul class=\"pubblicazioni-list\"><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/1330830\" target=\"_blank\" rel=\"noopener noreferrer\">Biodegradable films coated with Chitosan-based\/curcumin layer as active food packaging<\/a> <span class=\"pub-details\">(Cappello, Miriam; Barbani, Niccoletta; Malik, Neetu; Rossino, Dawid; Cristallini, Caterina; Trouki, Cheherazade; Cinelli, Patrizia - 2025 - 4.2 Abstract in Atti di convegno)<\/span><\/li><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/1330829\" target=\"_blank\" rel=\"noopener noreferrer\">Chitosan-Curcumin Coatings for Enhanced Food Preservation<\/a> <span class=\"pub-details\">(Cappello, Miriam; Barbani, Niccoletta; Trouki, Cheherazade; Rossino, Dawid; Cristallini, Caterina; Ferretti, Camilla; Malik, Neetu; Cinelli, Patrizia - 2025 - 4.1 Contributo in Atti di convegno)<\/span><\/li><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/1174965\" target=\"_blank\" rel=\"noopener noreferrer\">Characterization of Cyclic Olefin Copolymers for Insulin Reservoir in an Artificial Pancreas<\/a> <span class=\"pub-details\">(Mallegni, Norma; Milazzo, Mario; Cristallini, Caterina; Barbani, Niccoletta; Fredi, Giulia; Dorigato, Andrea; Cinelli, Patrizia; Danti, Serena - 2023 - 1.1 Articolo in rivista)<\/span><\/li><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/1140173\" target=\"_blank\" rel=\"noopener noreferrer\">Characterization of TOPAS for the design of an insulin reservoir in a robotic implant<\/a> <span class=\"pub-details\">(Lazzeri, Andrea; D&#039;Ambrosio, Roberto; Panariello, Luca; Ricci, Claudio; Sandroni, Marco; Barbani, Niccoletta; Cristallini, Caterina; Danti, Serena; Cinelli, Patrizia - 2019 - 4.2 Abstract in Atti di convegno)<\/span><\/li><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/1080922\" target=\"_blank\" rel=\"noopener noreferrer\">Biodegradable microparticles designed to efficiently reach and act on cystic fibrosis mucus barrier<\/a> <span class=\"pub-details\">(Cristallini, Caterina; Barbani, Niccoletta; Ventrelli, Letizia; Summa, Chiara; Filippi, Sara; Capel\u00f4a, Tania; Vitale, Emanuela; Albera, Carlo; Messore, Barbara; Giachino, Claudia - 2019 - 1.1 Articolo in rivista)<\/span><\/li><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/1032254\" target=\"_blank\" rel=\"noopener noreferrer\">Multifunctional coatings for robotic implanted device<\/a> <span class=\"pub-details\">(Cristallini, C.; Danti, S.; Azimi, B.; Tempesti, V.; Ricci, C.; Ventrelli, L.; Cinelli, P.; Barbani, N.; Lazzeri, A. - 2019 - 1.1 Articolo in rivista)<\/span><\/li><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/821491\" target=\"_blank\" rel=\"noopener noreferrer\">Surface chemical immobilization of bioactive peptides on synthetic polymers for cardiac tissue engineering<\/a> <span class=\"pub-details\">(Rosellini, Elisabetta; Cristallini, Caterina; Guerra, Giulio D.; Barbani, Niccoletta - 2015 - 1.1 Articolo in rivista)<\/span><\/li><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/754461\" target=\"_blank\" rel=\"noopener noreferrer\">Folic Acid-Conjugated Polymeric Nanoparticles for the DNA Active Targeting<\/a> <span class=\"pub-details\">(Bellotti, Elena; Barbani, Niccoletta; Cascone, MARIA GRAZIA; Cristallini, Caterina - 2015 - 4.1 Contributo in Atti di convegno)<\/span><\/li><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/496469\" target=\"_blank\" rel=\"noopener noreferrer\">Can the ABP-imprinted membranes make regress the amyloid deposition?<\/a> <span class=\"pub-details\">(Cristallini, Caterina; Bellotti, Elena; F., Spezia; Rosellini, Elisabetta; Cascone, MARIA GRAZIA; Barbani, Niccoletta - 2014 - 2.1 Contributo in volume (Capitolo o Saggio))<\/span><\/li><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/496273\" target=\"_blank\" rel=\"noopener noreferrer\">Development and characterization of new intelligent nanoparticles for drug targeting<\/a> <span class=\"pub-details\">(Bellotti, Elena; Barbani, Niccoletta; Cascone, MARIA GRAZIA; Cristallini, Caterina - 2014 - 2.1 Contributo in volume (Capitolo o Saggio))<\/span><\/li><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/386870\" target=\"_blank\" rel=\"noopener noreferrer\">Design and characterization of bi-functionalized scaffolds for blood vessels tissues<\/a> <span class=\"pub-details\">(Rosellini, Elisabetta; Cascone, MARIA GRAZIA; Lazzeri, Luigi; A., Hilfiker; M., Lux; L., Caron; Cristallini, Caterina; Barbani, Niccoletta - 2013 - 4.1 Contributo in Atti di convegno)<\/span><\/li><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/386867\" target=\"_blank\" rel=\"noopener noreferrer\">Bi-functionalized gelatin\/gellan\/elastin tubular scaffolds for blood vessels tissue engineering,<\/a> <span class=\"pub-details\">(Rosellini, Elisabetta; Cascone, MARIA GRAZIA; Lazzeri, Luigi; A., Hilfiker; M., Lux; L., Caron; Cristallini, Caterina; Barbani, Niccoletta - 2012 - 4.1 Contributo in Atti di convegno)<\/span><\/li><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/190514\" target=\"_blank\" rel=\"noopener noreferrer\">Kinetics and reaction mechanism of template polymerization investigated by conductimetric measurements: 2. The radical polymerization of sodium methacrylate in the presence of poy[allylamine] hydrochloride<\/a> <span class=\"pub-details\">(Cristallini, Caterina; G., Ciardelli; Polacco, Giovanni; A., Villani; Lazzeri, Luigi; Giusti, Paolo - 1999 - 1.1 Articolo in rivista)<\/span><\/li><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/202838\" target=\"_blank\" rel=\"noopener noreferrer\">Interactions in hyaluronic acid-polyethyleneoxide blends<\/a> <span class=\"pub-details\">(Barbani, Niccoletta; Pizzirani, Giovanna; Cristallini, Caterina; Polacco, Giovanni; Lazzeri, Luigi - 1997 - 4.1 Contributo in Atti di convegno)<\/span><\/li><li><a href=\"https:\/\/arpi.unipi.it\/handle\/11568\/182566\" target=\"_blank\" rel=\"noopener noreferrer\">Dextran\/Poly[acrylic acid] blends as potential biomaterials<\/a> <span class=\"pub-details\">(Polacco, Giovanni; Cristallini, Caterina; Maltinti, S; Cascone, MARIA GRAZIA - 1997 - 4.1 Contributo in Atti di convegno)<\/span><\/li><\/ul>","unipi-persone-didattica":"<ul class=\"registri-list\"><li>Laboratory of materials characterization (cod. 999II) per Laurea Magistrale in Materials and nanotechnology<\/li><li>Nanomedicine and regenerative medicine (cod. 1053I) per Laurea Magistrale in Materials and nanotechnology<\/li><\/ul>"},"organizzazioni":[],"class_list":["post-184529","unipi_persone","type-unipi_persone","status-publish","hentry"],"email":"C.CRISTALLINI@ING.UNIPI.IT","telefono":null,"content_plain":"Docente Esterno | Email: C.CRISTALLINI@ING.UNIPI.IT","photo_url":null,"ruoli_tags":[{"id":745,"name":"DE","slug":"de"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caterina Cristallini ~ UNIPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caterina Cristallini ~ UNIPI\" \/>\n<meta property=\"og:description\" content=\"Docente Esterno | Email: C.CRISTALLINI@ING.UNIPI.IT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIPI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unipisaofficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T02:36:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/\",\"url\":\"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/\",\"name\":\"Caterina Cristallini ~ UNIPI\",\"isPartOf\":{\"@id\":\"https:\/\/www.unipi.it\/en\/#website\"},\"datePublished\":\"2025-07-05T23:49:18+00:00\",\"dateModified\":\"2026-04-01T02:36:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\/\/www.unipi.it\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caterina Cristallini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.unipi.it\/en\/#website\",\"url\":\"https:\/\/www.unipi.it\/en\/\",\"name\":\"UNIPI\",\"description\":\"UNIPI\",\"publisher\":{\"@id\":\"https:\/\/www.unipi.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.unipi.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.unipi.it\/en\/#organization\",\"name\":\"UNIPI\",\"url\":\"https:\/\/www.unipi.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.unipi.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.unipi.it\/wp-content\/uploads\/Raggruppa-3020.svg\",\"contentUrl\":\"https:\/\/www.unipi.it\/wp-content\/uploads\/Raggruppa-3020.svg\",\"width\":176,\"height\":64,\"caption\":\"UNIPI\"},\"image\":{\"@id\":\"https:\/\/www.unipi.it\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/unipisaofficial\/\",\"https:\/\/www.instagram.com\/unipisa\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caterina Cristallini ~ UNIPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/","og_locale":"en_US","og_type":"article","og_title":"Caterina Cristallini ~ UNIPI","og_description":"Docente Esterno | Email: C.CRISTALLINI@ING.UNIPI.IT","og_url":"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/","og_site_name":"UNIPI","article_publisher":"https:\/\/www.facebook.com\/unipisaofficial\/","article_modified_time":"2026-04-01T02:36:47+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/","url":"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/","name":"Caterina Cristallini ~ UNIPI","isPartOf":{"@id":"https:\/\/www.unipi.it\/en\/#website"},"datePublished":"2025-07-05T23:49:18+00:00","dateModified":"2026-04-01T02:36:47+00:00","breadcrumb":{"@id":"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/caterina-cristallini-84905-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.unipi.it\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Caterina Cristallini"}]},{"@type":"WebSite","@id":"https:\/\/www.unipi.it\/en\/#website","url":"https:\/\/www.unipi.it\/en\/","name":"UNIPI","description":"UNIPI","publisher":{"@id":"https:\/\/www.unipi.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unipi.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.unipi.it\/en\/#organization","name":"UNIPI","url":"https:\/\/www.unipi.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unipi.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.unipi.it\/wp-content\/uploads\/Raggruppa-3020.svg","contentUrl":"https:\/\/www.unipi.it\/wp-content\/uploads\/Raggruppa-3020.svg","width":176,"height":64,"caption":"UNIPI"},"image":{"@id":"https:\/\/www.unipi.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unipisaofficial\/","https:\/\/www.instagram.com\/unipisa\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/unipi_persone\/184529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/unipi_persone"}],"about":[{"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/types\/unipi_persone"}],"wp:attachment":[{"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/media?parent=184529"}],"wp:term":[{"taxonomy":"organizzazioni","embeddable":true,"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/organizzazioni?post=184529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}