{"id":141945,"date":"2025-05-12T13:46:37","date_gmt":"2025-05-12T13:46:37","guid":{"rendered":"https:\/\/www.unipi.it\/ateneo\/organizzazione\/persone\/nausicaa-bertellotti-194618-en\/"},"modified":"2026-03-13T04:35:32","modified_gmt":"2026-03-13T03:35:32","slug":"nausicaa-bertellotti-194618-en","status":"publish","type":"unipi_persone","link":"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/","title":{"rendered":"Nausicaa Bertellotti"},"content":{"rendered":"<p>Dottorando &#8211; Dottorati Interesse Nazionale (din)<\/p>\n","protected":false},"template":"","meta":{"unipi-persone-chiave":"194618","unipi-persone-nome":"Nausicaa","unipi-persone-cognome":"Bertellotti","unipi-persone-email":"","unipi-persone-cv":"","unipi-persone-link-esterno-cv":"","unipi-persone-modalita-ricevimento":"","unipi-persone-luogo-ricevimento":"","unipi-persone-ore-ricevimento":"","unipi-persone-telefono":"","unipi-persone-sitoweb":"","unipi-persone-cariche":"","unipi-persone-link-orario-lezioni":"","unipi-persone-link-registro-lezioni":"","unipi-persone-settore-scientifico":"","unipi-persone-ruolo":"Dottorando","unipi-persone-arpi":null,"unipi-persone-pubblicazioni":"","unipi-persone-didattica":"","unipi-persone-codocenze":"","unipi-persone-interessi-ricerca":"","_wpml_word_count":"12","_last_translation_edit_mode":"translation-editor","unipi-persone-dati-posizione":""},"organizzazioni":[],"class_list":["post-141945","unipi_persone","type-unipi_persone","status-publish","hentry"],"email":null,"telefono":null,"content_plain":"Dottorando &#8211; Dottorati Interesse Nazionale (din)","photo_url":null,"ruoli_tags":[{"id":749,"name":"DR","slug":"dr"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nausicaa Bertellotti ~ UNIPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nausicaa Bertellotti ~ UNIPI\" \/>\n<meta property=\"og:description\" content=\"Dottorando &#8211; Dottorati Interesse Nazionale (din)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIPI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unipisaofficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T03:35:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/\",\"url\":\"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/\",\"name\":\"Nausicaa Bertellotti ~ UNIPI\",\"isPartOf\":{\"@id\":\"https:\/\/www.unipi.it\/en\/#website\"},\"datePublished\":\"2025-05-12T13:46:37+00:00\",\"dateModified\":\"2026-03-13T03:35:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\/\/www.unipi.it\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nausicaa Bertellotti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.unipi.it\/en\/#website\",\"url\":\"https:\/\/www.unipi.it\/en\/\",\"name\":\"UNIPI\",\"description\":\"UNIPI\",\"publisher\":{\"@id\":\"https:\/\/www.unipi.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.unipi.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.unipi.it\/en\/#organization\",\"name\":\"UNIPI\",\"url\":\"https:\/\/www.unipi.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.unipi.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.unipi.it\/wp-content\/uploads\/Raggruppa-3020.svg\",\"contentUrl\":\"https:\/\/www.unipi.it\/wp-content\/uploads\/Raggruppa-3020.svg\",\"width\":176,\"height\":64,\"caption\":\"UNIPI\"},\"image\":{\"@id\":\"https:\/\/www.unipi.it\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/unipisaofficial\/\",\"https:\/\/www.instagram.com\/unipisa\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nausicaa Bertellotti ~ UNIPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/","og_locale":"en_US","og_type":"article","og_title":"Nausicaa Bertellotti ~ UNIPI","og_description":"Dottorando &#8211; Dottorati Interesse Nazionale (din)","og_url":"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/","og_site_name":"UNIPI","article_publisher":"https:\/\/www.facebook.com\/unipisaofficial\/","article_modified_time":"2026-03-13T03:35:32+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/","url":"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/","name":"Nausicaa Bertellotti ~ UNIPI","isPartOf":{"@id":"https:\/\/www.unipi.it\/en\/#website"},"datePublished":"2025-05-12T13:46:37+00:00","dateModified":"2026-03-13T03:35:32+00:00","breadcrumb":{"@id":"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.unipi.it\/en\/about-us\/organisation\/people\/nausicaa-bertellotti-194618-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.unipi.it\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Nausicaa Bertellotti"}]},{"@type":"WebSite","@id":"https:\/\/www.unipi.it\/en\/#website","url":"https:\/\/www.unipi.it\/en\/","name":"UNIPI","description":"UNIPI","publisher":{"@id":"https:\/\/www.unipi.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unipi.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.unipi.it\/en\/#organization","name":"UNIPI","url":"https:\/\/www.unipi.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unipi.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.unipi.it\/wp-content\/uploads\/Raggruppa-3020.svg","contentUrl":"https:\/\/www.unipi.it\/wp-content\/uploads\/Raggruppa-3020.svg","width":176,"height":64,"caption":"UNIPI"},"image":{"@id":"https:\/\/www.unipi.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unipisaofficial\/","https:\/\/www.instagram.com\/unipisa\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/unipi_persone\/141945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/unipi_persone"}],"about":[{"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/types\/unipi_persone"}],"wp:attachment":[{"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/media?parent=141945"}],"wp:term":[{"taxonomy":"organizzazioni","embeddable":true,"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/organizzazioni?post=141945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}