{"id":175382,"date":"2024-11-12T10:51:27","date_gmt":"2024-11-12T10:51:27","guid":{"rendered":"https:\/\/www.unipi.it\/education\/courses\/corsi-di-perfezionamento\/"},"modified":"2025-06-20T09:16:15","modified_gmt":"2025-06-20T07:16:15","slug":"advanced-courses","status":"publish","type":"page","link":"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/","title":{"rendered":"Advanced Courses"},"content":{"rendered":"<p>Advanced courses are professional development programs of varying duration, open to individuals who have completed either a bachelor&#8217;s or a master&#8217;s degree.<\/p>\n<p>They are established in accordance with the \u201c<a href=\"https:\/\/www.unipi.it\/index.php\/component\/phocadownload\/category\/6-area-didattica-e-studenti?download=638:linee-guida-per-lattivazione-dei-corsi-di-perfezionamento\" target=\"_blank\" rel=\"noopener\">Guidelines for the Activation of Advanced Training Courses<\/a>\u201d (Academic Senate Resolution No. 123, dated May 29, 2013).<\/p>\n<h2>Agricultural and Veterinary Sciences<\/h2>\n<ul>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/agritech-agricoltura-digitale-per-lo-sviluppo-sostenibile\/\">Agritech &#8211; Agricoltura digitale per lo sviluppo sostenibile<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/corso-pratico-di-ecografia-addominale\/\" target=\"_blank\" rel=\"noopener\">Corso pratico di ecografia addominale<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/formazione-specifica-per-il-personale-coinvolto-nella-sperimentazione-animale-per-fini-scientifici-equidi-e-bovino-2\/\" target=\"_blank\" rel=\"noopener\">Formazione specifica per il personale coinvolto nella sperimentazione animale per fini scientifici \u2013 equidi e bovino<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/metodi-sensoriali-per-le-tecnologie-alimentari-e-lalimentazione\/\">Metodi sensoriali per le tecnologie alimentari e l\u2019alimentazione<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/radiologia-toracica-del-cane-e-del-gatto\/\">Radiologia toracica del cane e del gatto<\/a><\/li>\n<\/ul>\n<h2>Humanities<\/h2>\n<ul>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/il-rievocatore-come-public-historian\/\">Il rievocatore come Public Historian<\/a><\/li>\n<\/ul>\n<h2>Engineering<\/h2>\n<ul>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/advanced-project-management-delivering-value-in-complex-environments\/\">Advanced Project Management: Delivering Value in Complex Environments<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/energy-systems\/\">Energy systems<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/transizione-energetica-nei-siti-patrimonio-unesco-e-nelle-citta-darte\/\">Transizione energetica nei siti Patrimonio UNESCO e nelle Citt\u00e0 d&#8217;Arte<\/a><\/li>\n<\/ul>\n<h2>Health Sciences<\/h2>\n<ul>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/comunicare-il-rischio-durante-le-emergenze-sanitarie-dallanalisi-delle-sfide-alla-gestione-dellinfodemia\/\">Comunicare il rischio durante le emergenze sanitarie: dall\u2019analisi delle sfide alla gestione dell\u2019infodemia<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/ecografia-di-base\/\">Ecografia di base<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/ecografia-in-ematologia\/\">Ecografia in ematologia<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/ecografia-muscoloscheletrica-della-scuola-siumb\/\">Ecografia muscoloscheletrica<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/elementi-medici-e-giuridici-per-il-riconoscimento-di-malattia-psichica-di-origine-occupazionale-nel-contenzioso-medico-legale\/\">Elementi medici e giuridici per il riconoscimento di malattia psichica di origine occupazionale nel contenzioso medico-legale<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/fine-vita-stati-di-coscienza-antiche-tradizioni-e-nuove-terapie\/\">Fine vita: stati di coscienza, antiche tradizioni e nuove terapie<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/genere-e-salute-promozione-delleguaglianza-e-valorizzazione-delle-differenze-nellorganizzazione-e-nella-pratica-clinica\/\">Genere e salute: promozione dell\u2019eguaglianza e valorizzazione delle differenze nell\u2019organizzazione e nella pratica clinica<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/impianto-cocleare-dalle-indicazioni-alla-chirurgia\/\">Impianto cocleare: dalle indicazioni alla chirurgia<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/implantologia-orale-ed-implantoprotesi\/\">Implantologia orale ed implantoprotesi<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/la-comunicazione-medico-paziente-nellera-digitale\/\">La comunicazione medico-paziente nell\u2019era digitale<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/la-mindfulness-psicosomatica-nelle-relazioni-di-aiuto-basi-teoriche-e-pratiche-per-ridurre-lo-stress-e-riconnettere-corpo-mente-ed-emozioni\/\">La Mindfulness Psicosomatica nelle relazioni di aiuto: basi teoriche e pratiche per ridurre lo stress e riconnettere corpo, mente ed emozioni<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/la-terapia-compressiva-nel-paziente-con-patologie-vascolari-e-linfatiche-degli-arti\/\">La terapia compressiva nel paziente con patologie vascolari e linfatiche degli arti<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/metodologia-della-ricerca-scientifica-applicata-allesercizio-fisico-e-allo-sport\/\">Metodologia della ricerca scientifica applicata all\u2019esercizio fisico e allo sport<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/otologia\/\">Otologia<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/pratiche-dialogiche-nelle-organizzazioni-complesse-facilitatore-del-dialogo-per-team-e-gruppi\/\">Pratiche dialogiche nelle organizzazioni complesse. Facilitatore del dialogo per team e gruppi<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/performance-coaching-sport-management\/\">\u201cPerformance Coaching\u201d Sport &amp; Management<\/a><\/li>\n<li><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/studio-delle-mummie\/\">Studio delle mummie<\/a><\/li>\n<li aria-level=\"3\"><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/tecniche-chirurgiche-per-la-rivascolarizzazione-degli-arti-inferiori\/\">Tecniche chirurgiche per la rivascolarizzazione degli arti inferiori<\/a><\/li>\n<li aria-level=\"3\"><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/water-performance-and-recovery-approcci-integrati-per-la-rieducazione-e-la-performance-in-acqua\/\">Water Performance and Recovery: approcci integrati per la rieducazione e la performance in acqua<\/a><\/li>\n<\/ul>\n<h2>Social Sciences<\/h2>\n<ul>\n<li aria-level=\"3\"><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/co-progettazione-terzo-settore-e-welfare-partecipativo-metodi-e-tecniche-di-amministrazione-condivisa\/\">Co-progettazione, Terzo Settore e Welfare partecipativo. Metodi e tecniche di amministrazione condivisa<\/a><\/li>\n<li aria-level=\"3\"><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/la-rendicontazione-di-sostenibilita-secondo-gli-standard-europei-esrs\/\">La rendicontazione di sostenibilit\u00e0 secondo gli standard europei ESRS<\/a><\/li>\n<li aria-level=\"3\"><a href=\"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/business-and-human-rights-tools-for-responsible-management\/\">Business and Human Rights: Tools for Responsible Management\u00a0<\/a><\/li>\n<\/ul>\n<h2 aria-level=\"3\">Mathematical, Physical, Natural and Computer Sciences<\/h2>\n<ul>\n<li aria-level=\"3\"><a href=\"https:\/\/www.unipi.it\/didattica\/corsi\/corsi-di-perfezionamento\/ai-4-your-business\/\">AI 4 your business<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Advanced courses are professional development programs of varying duration, open to individuals who have completed either a bachelor&#8217;s or a master&#8217;s degree. They are established in accordance with the \u201cGuidelines for the Activation of Advanced Training Courses\u201d (Academic Senate Resolution No. 123, dated May 29, 2013). Agricultural and Veterinary Sciences Agritech &#8211; Agricoltura digitale per [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":25141,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"default-template.php","meta":{"footnotes":""},"class_list":["post-175382","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Advanced Courses ~ UNIPI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Advanced Courses ~ UNIPI\" \/>\n<meta property=\"og:description\" content=\"Advanced courses are professional development programs of varying duration, open to individuals who have completed either a bachelor&#8217;s or a master&#8217;s degree. They are established in accordance with the \u201cGuidelines for the Activation of Advanced Training Courses\u201d (Academic Senate Resolution No. 123, dated May 29, 2013). Agricultural and Veterinary Sciences Agritech &#8211; Agricoltura digitale per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/\" \/>\n<meta property=\"og:site_name\" content=\"UNIPI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/unipisaofficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T07:16:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/\",\"url\":\"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/\",\"name\":\"Advanced Courses ~ UNIPI\",\"isPartOf\":{\"@id\":\"https:\/\/www.unipi.it\/en\/#website\"},\"datePublished\":\"2024-11-12T10:51:27+00:00\",\"dateModified\":\"2025-06-20T07:16:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\/\/www.unipi.it\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Education\",\"item\":\"https:\/\/www.unipi.it\/en\/education\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Courses\",\"item\":\"https:\/\/www.unipi.it\/en\/education\/courses\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Advanced Courses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.unipi.it\/en\/#website\",\"url\":\"https:\/\/www.unipi.it\/en\/\",\"name\":\"UNIPI\",\"description\":\"UNIPI\",\"publisher\":{\"@id\":\"https:\/\/www.unipi.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.unipi.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.unipi.it\/en\/#organization\",\"name\":\"UNIPI\",\"url\":\"https:\/\/www.unipi.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.unipi.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.unipi.it\/wp-content\/uploads\/Raggruppa-3020.svg\",\"contentUrl\":\"https:\/\/www.unipi.it\/wp-content\/uploads\/Raggruppa-3020.svg\",\"width\":176,\"height\":64,\"caption\":\"UNIPI\"},\"image\":{\"@id\":\"https:\/\/www.unipi.it\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/unipisaofficial\/\",\"https:\/\/www.instagram.com\/unipisa\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Advanced Courses ~ UNIPI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/","og_locale":"en_US","og_type":"article","og_title":"Advanced Courses ~ UNIPI","og_description":"Advanced courses are professional development programs of varying duration, open to individuals who have completed either a bachelor&#8217;s or a master&#8217;s degree. They are established in accordance with the \u201cGuidelines for the Activation of Advanced Training Courses\u201d (Academic Senate Resolution No. 123, dated May 29, 2013). Agricultural and Veterinary Sciences Agritech &#8211; Agricoltura digitale per [&hellip;]","og_url":"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/","og_site_name":"UNIPI","article_publisher":"https:\/\/www.facebook.com\/unipisaofficial\/","article_modified_time":"2025-06-20T07:16:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/","url":"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/","name":"Advanced Courses ~ UNIPI","isPartOf":{"@id":"https:\/\/www.unipi.it\/en\/#website"},"datePublished":"2024-11-12T10:51:27+00:00","dateModified":"2025-06-20T07:16:15+00:00","breadcrumb":{"@id":"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.unipi.it\/en\/education\/courses\/advanced-courses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.unipi.it\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Education","item":"https:\/\/www.unipi.it\/en\/education\/"},{"@type":"ListItem","position":3,"name":"Courses","item":"https:\/\/www.unipi.it\/en\/education\/courses\/"},{"@type":"ListItem","position":4,"name":"Advanced Courses"}]},{"@type":"WebSite","@id":"https:\/\/www.unipi.it\/en\/#website","url":"https:\/\/www.unipi.it\/en\/","name":"UNIPI","description":"UNIPI","publisher":{"@id":"https:\/\/www.unipi.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unipi.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.unipi.it\/en\/#organization","name":"UNIPI","url":"https:\/\/www.unipi.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unipi.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.unipi.it\/wp-content\/uploads\/Raggruppa-3020.svg","contentUrl":"https:\/\/www.unipi.it\/wp-content\/uploads\/Raggruppa-3020.svg","width":176,"height":64,"caption":"UNIPI"},"image":{"@id":"https:\/\/www.unipi.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/unipisaofficial\/","https:\/\/www.instagram.com\/unipisa\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/pages\/175382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/comments?post=175382"}],"version-history":[{"count":10,"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/pages\/175382\/revisions"}],"predecessor-version":[{"id":175924,"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/pages\/175382\/revisions\/175924"}],"up":[{"embeddable":true,"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/pages\/25141"}],"wp:attachment":[{"href":"https:\/\/www.unipi.it\/en\/wp-json\/wp\/v2\/media?parent=175382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}